{"id":1809,"count":33,"description":"","link":"https:\/\/www.belotti.com\/es\/categoria\/noticias\/archivo\/","name":"Archivo","slug":"archivo","taxonomy":"category","parent":5,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archivo - Belotti<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.belotti.com\/es\/categoria\/noticias\/archivo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archivo - Belotti\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.belotti.com\/es\/categoria\/noticias\/archivo\/\" \/>\n<meta property=\"og:site_name\" content=\"Belotti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Belotti__SPA\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/es\\\/categoria\\\/noticias\\\/archivo\\\/\",\"url\":\"https:\\\/\\\/www.belotti.com\\\/es\\\/categoria\\\/noticias\\\/archivo\\\/\",\"name\":\"Archivo - Belotti\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/es\\\/categoria\\\/noticias\\\/archivo\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/es\\\/categoria\\\/noticias\\\/archivo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.belotti.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/www.belotti.com\\\/es\\\/categoria\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Archivo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.belotti.com\\\/es\\\/\",\"name\":\"Belotti Spa\",\"description\":\"CNC Machining Centers\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.belotti.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/es\\\/#organization\",\"name\":\"Belotti Spa\",\"url\":\"https:\\\/\\\/www.belotti.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/belotti.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo-Belotti-1.png\",\"contentUrl\":\"http:\\\/\\\/belotti.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo-Belotti-1.png\",\"width\":708,\"height\":225,\"caption\":\"Belotti Spa\"},\"image\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Belotti.SPA\",\"https:\\\/\\\/x.com\\\/Belotti__SPA\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC5q7E8IMymZ-agKfVsPCorw\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/belotti-s-p-a-\\\/?viewAsMember=true\",\"https:\\\/\\\/www.instagram.com\\\/belotti_spa\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archivo - Belotti","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.belotti.com\/es\/categoria\/noticias\/archivo\/","og_locale":"es_ES","og_type":"article","og_title":"Archivo - Belotti","og_url":"https:\/\/www.belotti.com\/es\/categoria\/noticias\/archivo\/","og_site_name":"Belotti","twitter_card":"summary_large_image","twitter_site":"@Belotti__SPA","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.belotti.com\/es\/categoria\/noticias\/archivo\/","url":"https:\/\/www.belotti.com\/es\/categoria\/noticias\/archivo\/","name":"Archivo - Belotti","isPartOf":{"@id":"https:\/\/www.belotti.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.belotti.com\/es\/categoria\/noticias\/archivo\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.belotti.com\/es\/categoria\/noticias\/archivo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.belotti.com\/es\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/www.belotti.com\/es\/categoria\/noticias\/"},{"@type":"ListItem","position":3,"name":"Archivo"}]},{"@type":"WebSite","@id":"https:\/\/www.belotti.com\/es\/#website","url":"https:\/\/www.belotti.com\/es\/","name":"Belotti Spa","description":"CNC Machining Centers","publisher":{"@id":"https:\/\/www.belotti.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.belotti.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.belotti.com\/es\/#organization","name":"Belotti Spa","url":"https:\/\/www.belotti.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.belotti.com\/es\/#\/schema\/logo\/image\/","url":"http:\/\/belotti.com\/wp-content\/uploads\/2023\/04\/logo-Belotti-1.png","contentUrl":"http:\/\/belotti.com\/wp-content\/uploads\/2023\/04\/logo-Belotti-1.png","width":708,"height":225,"caption":"Belotti Spa"},"image":{"@id":"https:\/\/www.belotti.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Belotti.SPA","https:\/\/x.com\/Belotti__SPA","https:\/\/www.youtube.com\/channel\/UC5q7E8IMymZ-agKfVsPCorw","https:\/\/www.linkedin.com\/company\/belotti-s-p-a-\/?viewAsMember=true","https:\/\/www.instagram.com\/belotti_spa\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.belotti.com\/es\/wp-json\/wp\/v2\/categories\/1809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.belotti.com\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.belotti.com\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.belotti.com\/es\/wp-json\/wp\/v2\/categories\/5"}],"wp:post_type":[{"href":"https:\/\/www.belotti.com\/es\/wp-json\/wp\/v2\/posts?categories=1809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}