{"id":24150,"date":"2025-03-17T10:30:12","date_gmt":"2025-03-17T09:30:12","guid":{"rendered":"https:\/\/belotti.com\/?p=24150"},"modified":"2026-01-08T12:11:07","modified_gmt":"2026-01-08T11:11:07","slug":"belotti-et-antonio-fuoco-prets-a-courir-une-nouvelle-saison-ensemble","status":"publish","type":"post","link":"https:\/\/www.belotti.com\/fr\/belotti-et-antonio-fuoco-prets-a-courir-une-nouvelle-saison-ensemble\/","title":{"rendered":"Belotti et Antonio Fuoco : pr\u00eats \u00e0 courir une nouvelle saison ensemble !"},"content":{"rendered":"<p><strong>Le partenariat avec le pilote italien, initi\u00e9 l&rsquo;ann\u00e9e derni\u00e8re, est renouvel\u00e9 pour la saison 2025 du championnat FIA World Endurance Championship.<\/strong><\/p>\n<p>Il y a des victoires qui marquent les esprits, des \u00e9motions qui restent grav\u00e9es dans l&rsquo;histoire. <strong>Antonio Fuoco a \u00e9crit une page inoubliable du sport automobile<\/strong>, en remportant avec ses co\u00e9quipiers la prestigieuse \u00ab <strong>24 Heures du Mans 2024<\/strong> \u00bb avec la Ferrari 499P n\u00b0 50, d\u00e9montrant talent, d\u00e9termination et une passion tenace pour la vitesse.<\/p>\n<p>C&rsquo;est pourquoi, avec une immense fiert\u00e9, Belotti a d\u00e9cid\u00e9 de renouveler le partenariat avec Antonio, poursuivant un parcours qui va au-del\u00e0 de la simple collaboration : <strong>c&rsquo;est un partage de valeurs, d&rsquo;ambition, de recherche continue de la perfection<\/strong>. La course d&rsquo;endurance est un d\u00e9fi extr\u00eame, o\u00f9 chaque d\u00e9tail compte. Tout comme dans nos technologies, o\u00f9 pr\u00e9cision, innovation et performances sont les cl\u00e9s du succ\u00e8s. Et Antonio, avec son d\u00e9vouement et son esprit combatif, incarne parfaitement cette philosophie.<\/p>\n<p>Le championnat FIA WEC 2025 a \u00e9t\u00e9 inaugur\u00e9 le 28 f\u00e9vrier dernier sur le Circuit de Lusail avec le \u00ab <strong>Qatar 1812km<\/strong> \u00bb, o\u00f9 <strong>Antonio et ses coll\u00e8gues<\/strong> (Molina M., Nielsen N.) <strong>ont domin\u00e9 le podium lors de la course d&rsquo;ouverture<\/strong>. La saison se poursuivra ensuite en Italie, Belgique, France, Br\u00e9sil, \u00c9tats-Unis, Japon et Bahre\u00efn. Les passionn\u00e9s et les fans peuvent acc\u00e9der au programme complet sur le site officiel <a href=\"https:\/\/www.fiawec.com\/fr\/calendar\/80\" target=\"_blank\" rel=\"noopener\">FIA WEC<\/a>.<\/p>\n<p>Cette treizi\u00e8me saison du FIA World Endurance Championship verra la participation de <strong>18 Hypercars de neuf constructeurs<\/strong>, soulignant la croissance continue de la plus importante s\u00e9rie de courses d&rsquo;endurance au monde. Des noms prestigieux comme Alpine, Aston Martin (rempla\u00e7ant Lamborghini), BMW, Cadillac, Ferrari, Isotta Fraschini, Peugeot, Porsche et Toyota se disputeront la supr\u00e9matie sur les circuits internationaux cette saison.<\/p>\n<p><strong>Nous sommes pr\u00eats \u00e0 courir une nouvelle saison passionnante ensemble<\/strong>. En avant toute, Antonio !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le partenariat avec le pilote italien, initi\u00e9 l&rsquo;ann\u00e9e derni\u00e8re, est renouvel\u00e9 pour la saison 2025 du championnat FIA&#8230;<\/p>\n","protected":false},"author":3,"featured_media":24065,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2,1866],"tags":[1369,1370,1371,1372,1373,1374,1191,1199,1203],"class_list":["post-24150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salle-de-presse","category-2025-fr-salle","tag-24-heures-du-mans-2024","tag-pilote-antonio-fuoco","tag-qatar-1812km","tag-fia-wec-2025-fr","tag-ferrari-hypercar-fr","tag-ferrari-499p-50-fr","tag-belotti-spa-fr","tag-antonio-fuoco-fr","tag-pilota-antonio-fuoco-fr"],"acf":{"photo_gallery":{"galleria":[[]]}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Belotti et Antonio Fuoco : pr\u00eats \u00e0 courir une nouvelle saison ensemble ! - Belotti<\/title>\n<meta name=\"description\" content=\"Le partenariat avec le pilote italien, initi\u00e9 l&#039;ann\u00e9e derni\u00e8re, est renouvel\u00e9 pour la saison 2025 du championnat FIA World Endurance Championship. Il y a\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.belotti.com\/fr\/belotti-et-antonio-fuoco-prets-a-courir-une-nouvelle-saison-ensemble\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Belotti et Antonio Fuoco : pr\u00eats \u00e0 courir une nouvelle saison ensemble ! - Belotti\" \/>\n<meta property=\"og:description\" content=\"Le partenariat avec le pilote italien, initi\u00e9 l&#039;ann\u00e9e derni\u00e8re, est renouvel\u00e9 pour la saison 2025 du championnat FIA World Endurance Championship. Il y a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.belotti.com\/fr\/belotti-et-antonio-fuoco-prets-a-courir-une-nouvelle-saison-ensemble\/\" \/>\n<meta property=\"og:site_name\" content=\"Belotti\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Belotti.SPA\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-17T09:30:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-08T11:11:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.belotti.com\/wp-content\/uploads\/2025\/03\/Belotti_Antonio-Fuoco-Rinnovo-partnership-2025.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1267\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eleonora Marino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Belotti__SPA\" \/>\n<meta name=\"twitter:site\" content=\"@Belotti__SPA\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eleonora Marino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/fr\\\/belotti-et-antonio-fuoco-prets-a-courir-une-nouvelle-saison-ensemble\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/fr\\\/belotti-et-antonio-fuoco-prets-a-courir-une-nouvelle-saison-ensemble\\\/\"},\"author\":{\"name\":\"Eleonora Marino\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/fr\\\/#\\\/schema\\\/person\\\/59dd4c9f3a914fd557a57a4c56c1565e\"},\"headline\":\"Belotti et Antonio Fuoco : pr\u00eats \u00e0 courir une nouvelle saison ensemble !\",\"datePublished\":\"2025-03-17T09:30:12+00:00\",\"dateModified\":\"2026-01-08T11:11:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/fr\\\/belotti-et-antonio-fuoco-prets-a-courir-une-nouvelle-saison-ensemble\\\/\"},\"wordCount\":329,\"publisher\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/fr\\\/belotti-et-antonio-fuoco-prets-a-courir-une-nouvelle-saison-ensemble\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.belotti.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Belotti_Antonio-Fuoco-Rinnovo-partnership-2025.jpg\",\"keywords\":[\"24 Heures du Mans 2024\",\"pilote Antonio Fuoco\",\"Qatar 1812km\",\"FIA WEC 2025\",\"Ferrari Hypercar\",\"Ferrari 499P 50\",\"Belotti spa\",\"Antonio Fuoco\",\"pilota Antonio Fuoco\"],\"articleSection\":[\"Salle de presse\",\"2025\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/fr\\\/belotti-et-antonio-fuoco-prets-a-courir-une-nouvelle-saison-ensemble\\\/\",\"url\":\"https:\\\/\\\/www.belotti.com\\\/fr\\\/belotti-et-antonio-fuoco-prets-a-courir-une-nouvelle-saison-ensemble\\\/\",\"name\":\"Belotti et Antonio Fuoco : pr\u00eats \u00e0 courir une nouvelle saison ensemble ! - Belotti\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/fr\\\/belotti-et-antonio-fuoco-prets-a-courir-une-nouvelle-saison-ensemble\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/fr\\\/belotti-et-antonio-fuoco-prets-a-courir-une-nouvelle-saison-ensemble\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.belotti.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Belotti_Antonio-Fuoco-Rinnovo-partnership-2025.jpg\",\"datePublished\":\"2025-03-17T09:30:12+00:00\",\"dateModified\":\"2026-01-08T11:11:07+00:00\",\"description\":\"Le partenariat avec le pilote italien, initi\u00e9 l'ann\u00e9e derni\u00e8re, est renouvel\u00e9 pour la saison 2025 du championnat FIA World Endurance Championship. Il y a\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/fr\\\/belotti-et-antonio-fuoco-prets-a-courir-une-nouvelle-saison-ensemble\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.belotti.com\\\/fr\\\/belotti-et-antonio-fuoco-prets-a-courir-une-nouvelle-saison-ensemble\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/fr\\\/belotti-et-antonio-fuoco-prets-a-courir-une-nouvelle-saison-ensemble\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.belotti.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Belotti_Antonio-Fuoco-Rinnovo-partnership-2025.jpg\",\"contentUrl\":\"https:\\\/\\\/www.belotti.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Belotti_Antonio-Fuoco-Rinnovo-partnership-2025.jpg\",\"width\":1267,\"height\":720,\"caption\":\"Belotti SpA_Antonio Fuoco-partnership 2025\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/fr\\\/belotti-et-antonio-fuoco-prets-a-courir-une-nouvelle-saison-ensemble\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.belotti.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Belotti et Antonio Fuoco : pr\u00eats \u00e0 courir une nouvelle saison ensemble !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.belotti.com\\\/fr\\\/\",\"name\":\"Belotti Spa\",\"description\":\"CNC Machining Centers\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.belotti.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/fr\\\/#organization\",\"name\":\"Belotti Spa\",\"url\":\"https:\\\/\\\/www.belotti.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/belotti.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo-Belotti-1.png\",\"contentUrl\":\"http:\\\/\\\/belotti.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo-Belotti-1.png\",\"width\":708,\"height\":225,\"caption\":\"Belotti Spa\"},\"image\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Belotti.SPA\",\"https:\\\/\\\/x.com\\\/Belotti__SPA\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC5q7E8IMymZ-agKfVsPCorw\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/belotti-s-p-a-\\\/?viewAsMember=true\",\"https:\\\/\\\/www.instagram.com\\\/belotti_spa\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/fr\\\/#\\\/schema\\\/person\\\/59dd4c9f3a914fd557a57a4c56c1565e\",\"name\":\"Eleonora Marino\",\"sameAs\":[\"https:\\\/\\\/belotti.com\\\/it\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Belotti et Antonio Fuoco : pr\u00eats \u00e0 courir une nouvelle saison ensemble ! - Belotti","description":"Le partenariat avec le pilote italien, initi\u00e9 l'ann\u00e9e derni\u00e8re, est renouvel\u00e9 pour la saison 2025 du championnat FIA World Endurance Championship. Il y a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.belotti.com\/fr\/belotti-et-antonio-fuoco-prets-a-courir-une-nouvelle-saison-ensemble\/","og_locale":"fr_FR","og_type":"article","og_title":"Belotti et Antonio Fuoco : pr\u00eats \u00e0 courir une nouvelle saison ensemble ! - Belotti","og_description":"Le partenariat avec le pilote italien, initi\u00e9 l'ann\u00e9e derni\u00e8re, est renouvel\u00e9 pour la saison 2025 du championnat FIA World Endurance Championship. Il y a","og_url":"https:\/\/www.belotti.com\/fr\/belotti-et-antonio-fuoco-prets-a-courir-une-nouvelle-saison-ensemble\/","og_site_name":"Belotti","article_publisher":"https:\/\/www.facebook.com\/Belotti.SPA","article_published_time":"2025-03-17T09:30:12+00:00","article_modified_time":"2026-01-08T11:11:07+00:00","og_image":[{"width":1267,"height":720,"url":"https:\/\/www.belotti.com\/wp-content\/uploads\/2025\/03\/Belotti_Antonio-Fuoco-Rinnovo-partnership-2025.jpg","type":"image\/jpeg"}],"author":"Eleonora Marino","twitter_card":"summary_large_image","twitter_creator":"@Belotti__SPA","twitter_site":"@Belotti__SPA","twitter_misc":{"\u00c9crit par":"Eleonora Marino","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.belotti.com\/fr\/belotti-et-antonio-fuoco-prets-a-courir-une-nouvelle-saison-ensemble\/#article","isPartOf":{"@id":"https:\/\/www.belotti.com\/fr\/belotti-et-antonio-fuoco-prets-a-courir-une-nouvelle-saison-ensemble\/"},"author":{"name":"Eleonora Marino","@id":"https:\/\/www.belotti.com\/fr\/#\/schema\/person\/59dd4c9f3a914fd557a57a4c56c1565e"},"headline":"Belotti et Antonio Fuoco : pr\u00eats \u00e0 courir une nouvelle saison ensemble !","datePublished":"2025-03-17T09:30:12+00:00","dateModified":"2026-01-08T11:11:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.belotti.com\/fr\/belotti-et-antonio-fuoco-prets-a-courir-une-nouvelle-saison-ensemble\/"},"wordCount":329,"publisher":{"@id":"https:\/\/www.belotti.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.belotti.com\/fr\/belotti-et-antonio-fuoco-prets-a-courir-une-nouvelle-saison-ensemble\/#primaryimage"},"thumbnailUrl":"https:\/\/www.belotti.com\/wp-content\/uploads\/2025\/03\/Belotti_Antonio-Fuoco-Rinnovo-partnership-2025.jpg","keywords":["24 Heures du Mans 2024","pilote Antonio Fuoco","Qatar 1812km","FIA WEC 2025","Ferrari Hypercar","Ferrari 499P 50","Belotti spa","Antonio Fuoco","pilota Antonio Fuoco"],"articleSection":["Salle de presse","2025"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.belotti.com\/fr\/belotti-et-antonio-fuoco-prets-a-courir-une-nouvelle-saison-ensemble\/","url":"https:\/\/www.belotti.com\/fr\/belotti-et-antonio-fuoco-prets-a-courir-une-nouvelle-saison-ensemble\/","name":"Belotti et Antonio Fuoco : pr\u00eats \u00e0 courir une nouvelle saison ensemble ! - Belotti","isPartOf":{"@id":"https:\/\/www.belotti.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.belotti.com\/fr\/belotti-et-antonio-fuoco-prets-a-courir-une-nouvelle-saison-ensemble\/#primaryimage"},"image":{"@id":"https:\/\/www.belotti.com\/fr\/belotti-et-antonio-fuoco-prets-a-courir-une-nouvelle-saison-ensemble\/#primaryimage"},"thumbnailUrl":"https:\/\/www.belotti.com\/wp-content\/uploads\/2025\/03\/Belotti_Antonio-Fuoco-Rinnovo-partnership-2025.jpg","datePublished":"2025-03-17T09:30:12+00:00","dateModified":"2026-01-08T11:11:07+00:00","description":"Le partenariat avec le pilote italien, initi\u00e9 l'ann\u00e9e derni\u00e8re, est renouvel\u00e9 pour la saison 2025 du championnat FIA World Endurance Championship. Il y a","breadcrumb":{"@id":"https:\/\/www.belotti.com\/fr\/belotti-et-antonio-fuoco-prets-a-courir-une-nouvelle-saison-ensemble\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.belotti.com\/fr\/belotti-et-antonio-fuoco-prets-a-courir-une-nouvelle-saison-ensemble\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.belotti.com\/fr\/belotti-et-antonio-fuoco-prets-a-courir-une-nouvelle-saison-ensemble\/#primaryimage","url":"https:\/\/www.belotti.com\/wp-content\/uploads\/2025\/03\/Belotti_Antonio-Fuoco-Rinnovo-partnership-2025.jpg","contentUrl":"https:\/\/www.belotti.com\/wp-content\/uploads\/2025\/03\/Belotti_Antonio-Fuoco-Rinnovo-partnership-2025.jpg","width":1267,"height":720,"caption":"Belotti SpA_Antonio Fuoco-partnership 2025"},{"@type":"BreadcrumbList","@id":"https:\/\/www.belotti.com\/fr\/belotti-et-antonio-fuoco-prets-a-courir-une-nouvelle-saison-ensemble\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.belotti.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Belotti et Antonio Fuoco : pr\u00eats \u00e0 courir une nouvelle saison ensemble !"}]},{"@type":"WebSite","@id":"https:\/\/www.belotti.com\/fr\/#website","url":"https:\/\/www.belotti.com\/fr\/","name":"Belotti Spa","description":"CNC Machining Centers","publisher":{"@id":"https:\/\/www.belotti.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.belotti.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.belotti.com\/fr\/#organization","name":"Belotti Spa","url":"https:\/\/www.belotti.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.belotti.com\/fr\/#\/schema\/logo\/image\/","url":"http:\/\/belotti.com\/wp-content\/uploads\/2023\/04\/logo-Belotti-1.png","contentUrl":"http:\/\/belotti.com\/wp-content\/uploads\/2023\/04\/logo-Belotti-1.png","width":708,"height":225,"caption":"Belotti Spa"},"image":{"@id":"https:\/\/www.belotti.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Belotti.SPA","https:\/\/x.com\/Belotti__SPA","https:\/\/www.youtube.com\/channel\/UC5q7E8IMymZ-agKfVsPCorw","https:\/\/www.linkedin.com\/company\/belotti-s-p-a-\/?viewAsMember=true","https:\/\/www.instagram.com\/belotti_spa\/"]},{"@type":"Person","@id":"https:\/\/www.belotti.com\/fr\/#\/schema\/person\/59dd4c9f3a914fd557a57a4c56c1565e","name":"Eleonora Marino","sameAs":["https:\/\/belotti.com\/it\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.belotti.com\/fr\/wp-json\/wp\/v2\/posts\/24150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.belotti.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.belotti.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.belotti.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.belotti.com\/fr\/wp-json\/wp\/v2\/comments?post=24150"}],"version-history":[{"count":2,"href":"https:\/\/www.belotti.com\/fr\/wp-json\/wp\/v2\/posts\/24150\/revisions"}],"predecessor-version":[{"id":24183,"href":"https:\/\/www.belotti.com\/fr\/wp-json\/wp\/v2\/posts\/24150\/revisions\/24183"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.belotti.com\/fr\/wp-json\/wp\/v2\/media\/24065"}],"wp:attachment":[{"href":"https:\/\/www.belotti.com\/fr\/wp-json\/wp\/v2\/media?parent=24150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.belotti.com\/fr\/wp-json\/wp\/v2\/categories?post=24150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.belotti.com\/fr\/wp-json\/wp\/v2\/tags?post=24150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}