{"id":101,"date":"2020-12-10T10:16:21","date_gmt":"2020-12-10T09:16:21","guid":{"rendered":"https:\/\/belotti.com\/?page_id=101"},"modified":"2023-11-28T17:34:49","modified_gmt":"2023-11-28T16:34:49","slug":"stage-e-tirocini","status":"publish","type":"page","link":"https:\/\/www.belotti.com\/it\/careers\/stage-e-tirocini\/","title":{"rendered":"Stage e tirocini"},"content":{"rendered":"<p class=\"big\">Coniugare la teoria alla pratica, attraverso percorsi di stage o di tirocinio che avvicinino sempre di pi\u00f9 il mondo della scuola a quello del lavoro.<\/p>\n<p>Crediamo fortemente nel valore della formazione e nell\u2019importanza dell\u2019applicazione delle conoscenze all\u2019interno di un contesto aziendale.<br \/>\nPer questo motivo siamo sempre aperti ad accogliere studenti della scuola secondaria di secondo grado o studenti universitari che vogliano sviluppare le proprie competenze.<\/p>\n<p>Offriamo inoltre percorsi di alternanza scuola-lavoro con prospettive occupazionali, attivati in collaborazione con le scuole del territorio.<\/p>\n<p>Se sei interessato\/a ad un\u2019esperienza in Belotti inviaci il tuo curriculum.<\/p>\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f3544-o1\" lang=\"it-IT\" dir=\"ltr\" data-wpcf7-id=\"3544\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/it\/wp-json\/wp\/v2\/pages\/101#wpcf7-f3544-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Modulo di contatto\" enctype=\"multipart\/form-data\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"3544\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"it_IT\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f3544-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7cf_hidden_group_fields\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_hidden_groups\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_visible_groups\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_repeaters\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_steps\" value=\"{}\" \/><input type=\"hidden\" name=\"_wpcf7cf_options\" value=\"{&quot;form_id&quot;:3544,&quot;conditions&quot;:[],&quot;settings&quot;:{&quot;animation&quot;:&quot;yes&quot;,&quot;animation_intime&quot;:200,&quot;animation_outtime&quot;:200,&quot;conditions_ui&quot;:&quot;normal&quot;,&quot;notice_dismissed&quot;:false,&quot;repeater_remove_button&quot;:&quot;bottom&quot;,&quot;notice_dismissed_rollback-cf7-5.8.2&quot;:true}}\" \/><input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.5\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"uk-grid uk-grid-medium uk-child-width-1-2@s uk-flex-bottom\" uk-grid>\n\t<div>\n\t\t<p><label>Nome*<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"nome\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div>\n\t\t<p><label>Cognome*<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"cognome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"cognome\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div>\n\t\t<p><label>Email*<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div>\n\t\t<p><label>Telefono*<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"telefono\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"telefono\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div>\n\t\t<p><label>Ambito di interesse \/ Funzione aziendale*<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"ambito\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"ambito\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div>\n\t\t<p><label>Sede<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"dove\"><select class=\"wpcf7-form-control wpcf7-select\" aria-invalid=\"false\" name=\"dove\"><option value=\"\">-- Seleziona un&#039;opzione --<\/option><option value=\"Modena\">Modena<\/option><option value=\"Suisio (Bg)\">Suisio (Bg)<\/option><\/select><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div>\n\t\t<p><label>Allega il tuo curriculum*<span class=\"limiti\">Max 6MB. Tipologie file consentite: PDF, DOC, DOCX<\/span><\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"file-114\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file wpcf7-validates-as-required\" accept=\".pdf,.doc,.docx\" aria-required=\"true\" aria-invalid=\"false\" type=\"file\" name=\"file-114\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"uk-width-1-1\">\n\t\t<p><label>Messaggio\/Lettera accompagnatoria*<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"messaggio\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"messaggio\"><\/textarea><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"uk-width-1-1\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"privacy\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"privacy\" value=\"1\" aria-invalid=\"false\" \/><\/span><\/span><\/span><span class=\"testo-privacy\">* Acconsento al trattamento dei dati sopra raccolti per la finalit\u00e0 indicata in conformit\u00e0 con l\u2019<a href=\"https:\/\/www.belotti.com\/it\/privacy-policy\/\" title=\"Privacy Policy\" target=\"_blank\">Informativa sulla Privacy<\/a>. Il presente consenso pu\u00f2 essere revocato in qualsiasi momento con effetto per il futuro.<\/span><br \/>\n<span class=\"recaptcha\">Questo sito \u00e8 protetto da reCAPTCHA e si applicano le norme sulla <a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\">Privacy<\/a> ed i <a href=\"https:\/\/policies.google.com\/terms\" target=\"_blank\">Termini di servizio<\/a> di Google.<\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"uk-width-1-1\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Invia\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"49\"\/><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n\/* ]]> *\/\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Coniugare la teoria alla pratica, attraverso percorsi di stage o di tirocinio che avvicinino sempre di pi\u00f9 il&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":95,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-101","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stage e tirocini - Belotti<\/title>\n<meta name=\"description\" content=\"Coniugare la teoria alla pratica, attraverso percorsi di stage o di tirocinio che avvicinino sempre di pi\u00f9 il mondo della scuola a quello del lavoro.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.belotti.com\/it\/careers\/stage-e-tirocini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stage e tirocini - Belotti\" \/>\n<meta property=\"og:description\" content=\"Coniugare la teoria alla pratica, attraverso percorsi di stage o di tirocinio che avvicinino sempre di pi\u00f9 il mondo della scuola a quello del lavoro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.belotti.com\/it\/careers\/stage-e-tirocini\/\" \/>\n<meta property=\"og:site_name\" content=\"Belotti\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Belotti.SPA\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T16:34:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Belotti__SPA\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/careers\\\/stage-e-tirocini\\\/\",\"url\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/careers\\\/stage-e-tirocini\\\/\",\"name\":\"Stage e tirocini - Belotti\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#website\"},\"datePublished\":\"2020-12-10T09:16:21+00:00\",\"dateModified\":\"2023-11-28T16:34:49+00:00\",\"description\":\"Coniugare la teoria alla pratica, attraverso percorsi di stage o di tirocinio che avvicinino sempre di pi\u00f9 il mondo della scuola a quello del lavoro.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/careers\\\/stage-e-tirocini\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.belotti.com\\\/it\\\/careers\\\/stage-e-tirocini\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/careers\\\/stage-e-tirocini\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Careers\",\"item\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/careers\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Stage e tirocini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/\",\"name\":\"Belotti Spa\",\"description\":\"CNC Machining Centers\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#organization\",\"name\":\"Belotti Spa\",\"url\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/belotti.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo-Belotti-1.png\",\"contentUrl\":\"http:\\\/\\\/belotti.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo-Belotti-1.png\",\"width\":708,\"height\":225,\"caption\":\"Belotti Spa\"},\"image\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Belotti.SPA\",\"https:\\\/\\\/x.com\\\/Belotti__SPA\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC5q7E8IMymZ-agKfVsPCorw\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/belotti-s-p-a-\\\/?viewAsMember=true\",\"https:\\\/\\\/www.instagram.com\\\/belotti_spa\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stage e tirocini - Belotti","description":"Coniugare la teoria alla pratica, attraverso percorsi di stage o di tirocinio che avvicinino sempre di pi\u00f9 il mondo della scuola a quello del lavoro.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.belotti.com\/it\/careers\/stage-e-tirocini\/","og_locale":"it_IT","og_type":"article","og_title":"Stage e tirocini - Belotti","og_description":"Coniugare la teoria alla pratica, attraverso percorsi di stage o di tirocinio che avvicinino sempre di pi\u00f9 il mondo della scuola a quello del lavoro.","og_url":"https:\/\/www.belotti.com\/it\/careers\/stage-e-tirocini\/","og_site_name":"Belotti","article_publisher":"https:\/\/www.facebook.com\/Belotti.SPA","article_modified_time":"2023-11-28T16:34:49+00:00","twitter_card":"summary_large_image","twitter_site":"@Belotti__SPA","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.belotti.com\/it\/careers\/stage-e-tirocini\/","url":"https:\/\/www.belotti.com\/it\/careers\/stage-e-tirocini\/","name":"Stage e tirocini - Belotti","isPartOf":{"@id":"https:\/\/www.belotti.com\/it\/#website"},"datePublished":"2020-12-10T09:16:21+00:00","dateModified":"2023-11-28T16:34:49+00:00","description":"Coniugare la teoria alla pratica, attraverso percorsi di stage o di tirocinio che avvicinino sempre di pi\u00f9 il mondo della scuola a quello del lavoro.","breadcrumb":{"@id":"https:\/\/www.belotti.com\/it\/careers\/stage-e-tirocini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.belotti.com\/it\/careers\/stage-e-tirocini\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.belotti.com\/it\/careers\/stage-e-tirocini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.belotti.com\/it\/"},{"@type":"ListItem","position":2,"name":"Careers","item":"https:\/\/www.belotti.com\/it\/careers\/"},{"@type":"ListItem","position":3,"name":"Stage e tirocini"}]},{"@type":"WebSite","@id":"https:\/\/www.belotti.com\/it\/#website","url":"https:\/\/www.belotti.com\/it\/","name":"Belotti Spa","description":"CNC Machining Centers","publisher":{"@id":"https:\/\/www.belotti.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.belotti.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.belotti.com\/it\/#organization","name":"Belotti Spa","url":"https:\/\/www.belotti.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.belotti.com\/it\/#\/schema\/logo\/image\/","url":"http:\/\/belotti.com\/wp-content\/uploads\/2023\/04\/logo-Belotti-1.png","contentUrl":"http:\/\/belotti.com\/wp-content\/uploads\/2023\/04\/logo-Belotti-1.png","width":708,"height":225,"caption":"Belotti Spa"},"image":{"@id":"https:\/\/www.belotti.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Belotti.SPA","https:\/\/x.com\/Belotti__SPA","https:\/\/www.youtube.com\/channel\/UC5q7E8IMymZ-agKfVsPCorw","https:\/\/www.linkedin.com\/company\/belotti-s-p-a-\/?viewAsMember=true","https:\/\/www.instagram.com\/belotti_spa\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/pages\/101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/comments?post=101"}],"version-history":[{"count":1,"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/pages\/101\/revisions"}],"predecessor-version":[{"id":17451,"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/pages\/101\/revisions\/17451"}],"up":[{"embeddable":true,"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/pages\/95"}],"wp:attachment":[{"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/media?parent=101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}