{"id":11965,"date":"2022-03-21T14:35:41","date_gmt":"2022-03-21T13:35:41","guid":{"rendered":"https:\/\/belotti.com\/?p=11965"},"modified":"2023-11-24T17:20:22","modified_gmt":"2023-11-24T16:20:22","slug":"jec-world-appuntamento-a-maggio-2022","status":"publish","type":"post","link":"https:\/\/www.belotti.com\/it\/jec-world-appuntamento-a-maggio-2022\/","title":{"rendered":"JEC WORLD: APPUNTAMENTO A MAGGIO 2022"},"content":{"rendered":"<p>Dopo due anni di attesa siamo lieti di tornare ad esporre a <strong>JEC World<\/strong>, la <strong>fiera internazionale di riferimento per i materiali compositi e le loro applicazioni<\/strong>, dove sar\u00e0 possibile scoprire le ultime novit\u00e0 destinate a molteplici settori industriali quali: automobilistico, aerospaziale, nautico, medicale, design, ingegneria edile e molti altri.<br \/>\nLa fiera \u00e8 in programma<strong> dal 3 al 5 Maggio 2022 presso il centro espositivo Paris Nord Villepinte<\/strong>.<\/p>\n<p>Per la prima volta l\u2019ente fiera metter\u00e0 a disposizione di espositori e visitatori <strong>JEC World Connect<\/strong>, una piattaforma digitale dove potersi incontrare all\u2019interno di uno stand virtuale. Una nuova soluzione sviluppata in seguito alla situazione pandemica dell\u2019ultimo biennio per poter sfruttare al massimo le opportunit\u00e0 di business offerte dall\u2019evento.<\/p>\n<p>All\u2019interno del nostro spazio espositivo, situato nel <strong>Padiglione 6 \u2013 stand n. G51<\/strong>, sar\u00e0 possibile entrare in contatto con tutte le business units Belotti e conoscere l\u2019offerta sempre pi\u00f9 articolata a completa: dai <a href=\"https:\/\/www.belotti.com\/it\/le-lavorazioni-di-fresatura-con-i-centri-di-lavoro-a-controllo-numerico-belotti\/\"><strong>centri a controllo numerico per la lavorazione dei materiali compositi<\/strong><\/a>, ai <strong>software IoT<\/strong> per la loro integrazione nell\u2019ambiente fabbrica, dalle<strong> linee e celle robotizzate <\/strong>progettate dalla<strong> divisione Belotti Robotic Automation<\/strong> ai <strong>Servizi After Sales<\/strong> dedicati ai clienti.<\/p>\n<p>I riflettori saranno certamente puntati su <strong>BEAD<\/strong>, la soluzione che integra in un unico centro di lavoro la stampa additiva di grande formato (LSAM) con il processo di fresatura sui materiali termoplastici fibro-rinforzati. Ogni giorno, presso lo stand, saranno organizzate sessioni di <strong>LIVE DEMO<\/strong> per scoprire direttamente le numerose potenzialit\u00e0 offerte da questa tecnologia.<\/p>\n<p>Scrivete a <a href=\"mailto:marketing@belotti.com\">marketing@belotti.com<\/a> per ricevere l&#8217;invito e registrarvi all&#8217;evento.<\/p>\n<p>Per maggiori informazioni sulla fiera: <a href=\"https:\/\/www.jec-world.events\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.jec-world.events\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo due anni di attesa siamo lieti di tornare ad esporre a JEC World, la fiera internazionale di&#8230;<\/p>\n","protected":false},"author":1,"featured_media":7758,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[73,9,707],"tags":[],"class_list":["post-11965","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-2","category-eventi","category-2022-it"],"acf":{"photo_gallery":{"galleria":[[]]}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>JEC WORLD: APPUNTAMENTO A MAGGIO 2022 - Belotti<\/title>\n<meta name=\"description\" content=\"Dopo due anni di attesa siamo lieti di tornare ad esporre a JEC World, la fiera internazionale di riferimento per i materiali compositi e le loro\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.belotti.com\/it\/jec-world-appuntamento-a-maggio-2022\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JEC WORLD: APPUNTAMENTO A MAGGIO 2022 - Belotti\" \/>\n<meta property=\"og:description\" content=\"Dopo due anni di attesa siamo lieti di tornare ad esporre a JEC World, la fiera internazionale di riferimento per i materiali compositi e le loro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.belotti.com\/it\/jec-world-appuntamento-a-maggio-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Belotti\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Belotti.SPA\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-21T13:35:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-24T16:20:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.belotti.com\/wp-content\/uploads\/2022\/02\/belotti-jec-2022-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"790\" \/>\n\t<meta property=\"og:image:height\" content=\"446\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"metodo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Belotti__SPA\" \/>\n<meta name=\"twitter:site\" content=\"@Belotti__SPA\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"metodo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/jec-world-appuntamento-a-maggio-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/jec-world-appuntamento-a-maggio-2022\\\/\"},\"author\":{\"name\":\"metodo\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#\\\/schema\\\/person\\\/b82447a049f0af88c70ba782b607ced6\"},\"headline\":\"JEC WORLD: APPUNTAMENTO A MAGGIO 2022\",\"datePublished\":\"2022-03-21T13:35:41+00:00\",\"dateModified\":\"2023-11-24T16:20:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/jec-world-appuntamento-a-maggio-2022\\\/\"},\"wordCount\":269,\"publisher\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/jec-world-appuntamento-a-maggio-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.belotti.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/belotti-jec-2022-1.jpg\",\"articleSection\":[\"Archivio\",\"Eventi\",\"2022\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/jec-world-appuntamento-a-maggio-2022\\\/\",\"url\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/jec-world-appuntamento-a-maggio-2022\\\/\",\"name\":\"JEC WORLD: APPUNTAMENTO A MAGGIO 2022 - Belotti\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/jec-world-appuntamento-a-maggio-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/jec-world-appuntamento-a-maggio-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.belotti.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/belotti-jec-2022-1.jpg\",\"datePublished\":\"2022-03-21T13:35:41+00:00\",\"dateModified\":\"2023-11-24T16:20:22+00:00\",\"description\":\"Dopo due anni di attesa siamo lieti di tornare ad esporre a JEC World, la fiera internazionale di riferimento per i materiali compositi e le loro\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/jec-world-appuntamento-a-maggio-2022\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.belotti.com\\\/it\\\/jec-world-appuntamento-a-maggio-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/jec-world-appuntamento-a-maggio-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.belotti.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/belotti-jec-2022-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.belotti.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/belotti-jec-2022-1.jpg\",\"width\":790,\"height\":446,\"caption\":\"belotti-jec\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/jec-world-appuntamento-a-maggio-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"JEC WORLD: APPUNTAMENTO A MAGGIO 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/\",\"name\":\"Belotti Spa\",\"description\":\"CNC Machining Centers\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#organization\",\"name\":\"Belotti Spa\",\"url\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/belotti.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo-Belotti-1.png\",\"contentUrl\":\"http:\\\/\\\/belotti.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo-Belotti-1.png\",\"width\":708,\"height\":225,\"caption\":\"Belotti Spa\"},\"image\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Belotti.SPA\",\"https:\\\/\\\/x.com\\\/Belotti__SPA\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC5q7E8IMymZ-agKfVsPCorw\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/belotti-s-p-a-\\\/?viewAsMember=true\",\"https:\\\/\\\/www.instagram.com\\\/belotti_spa\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#\\\/schema\\\/person\\\/b82447a049f0af88c70ba782b607ced6\",\"name\":\"metodo\",\"sameAs\":[\"https:\\\/\\\/metodoadv.com\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"JEC WORLD: APPUNTAMENTO A MAGGIO 2022 - Belotti","description":"Dopo due anni di attesa siamo lieti di tornare ad esporre a JEC World, la fiera internazionale di riferimento per i materiali compositi e le loro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.belotti.com\/it\/jec-world-appuntamento-a-maggio-2022\/","og_locale":"it_IT","og_type":"article","og_title":"JEC WORLD: APPUNTAMENTO A MAGGIO 2022 - Belotti","og_description":"Dopo due anni di attesa siamo lieti di tornare ad esporre a JEC World, la fiera internazionale di riferimento per i materiali compositi e le loro","og_url":"https:\/\/www.belotti.com\/it\/jec-world-appuntamento-a-maggio-2022\/","og_site_name":"Belotti","article_publisher":"https:\/\/www.facebook.com\/Belotti.SPA","article_published_time":"2022-03-21T13:35:41+00:00","article_modified_time":"2023-11-24T16:20:22+00:00","og_image":[{"width":790,"height":446,"url":"https:\/\/www.belotti.com\/wp-content\/uploads\/2022\/02\/belotti-jec-2022-1.jpg","type":"image\/jpeg"}],"author":"metodo","twitter_card":"summary_large_image","twitter_creator":"@Belotti__SPA","twitter_site":"@Belotti__SPA","twitter_misc":{"Scritto da":"metodo","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.belotti.com\/it\/jec-world-appuntamento-a-maggio-2022\/#article","isPartOf":{"@id":"https:\/\/www.belotti.com\/it\/jec-world-appuntamento-a-maggio-2022\/"},"author":{"name":"metodo","@id":"https:\/\/www.belotti.com\/it\/#\/schema\/person\/b82447a049f0af88c70ba782b607ced6"},"headline":"JEC WORLD: APPUNTAMENTO A MAGGIO 2022","datePublished":"2022-03-21T13:35:41+00:00","dateModified":"2023-11-24T16:20:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.belotti.com\/it\/jec-world-appuntamento-a-maggio-2022\/"},"wordCount":269,"publisher":{"@id":"https:\/\/www.belotti.com\/it\/#organization"},"image":{"@id":"https:\/\/www.belotti.com\/it\/jec-world-appuntamento-a-maggio-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/www.belotti.com\/wp-content\/uploads\/2022\/02\/belotti-jec-2022-1.jpg","articleSection":["Archivio","Eventi","2022"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.belotti.com\/it\/jec-world-appuntamento-a-maggio-2022\/","url":"https:\/\/www.belotti.com\/it\/jec-world-appuntamento-a-maggio-2022\/","name":"JEC WORLD: APPUNTAMENTO A MAGGIO 2022 - Belotti","isPartOf":{"@id":"https:\/\/www.belotti.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.belotti.com\/it\/jec-world-appuntamento-a-maggio-2022\/#primaryimage"},"image":{"@id":"https:\/\/www.belotti.com\/it\/jec-world-appuntamento-a-maggio-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/www.belotti.com\/wp-content\/uploads\/2022\/02\/belotti-jec-2022-1.jpg","datePublished":"2022-03-21T13:35:41+00:00","dateModified":"2023-11-24T16:20:22+00:00","description":"Dopo due anni di attesa siamo lieti di tornare ad esporre a JEC World, la fiera internazionale di riferimento per i materiali compositi e le loro","breadcrumb":{"@id":"https:\/\/www.belotti.com\/it\/jec-world-appuntamento-a-maggio-2022\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.belotti.com\/it\/jec-world-appuntamento-a-maggio-2022\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.belotti.com\/it\/jec-world-appuntamento-a-maggio-2022\/#primaryimage","url":"https:\/\/www.belotti.com\/wp-content\/uploads\/2022\/02\/belotti-jec-2022-1.jpg","contentUrl":"https:\/\/www.belotti.com\/wp-content\/uploads\/2022\/02\/belotti-jec-2022-1.jpg","width":790,"height":446,"caption":"belotti-jec"},{"@type":"BreadcrumbList","@id":"https:\/\/www.belotti.com\/it\/jec-world-appuntamento-a-maggio-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.belotti.com\/it\/"},{"@type":"ListItem","position":2,"name":"JEC WORLD: APPUNTAMENTO A MAGGIO 2022"}]},{"@type":"WebSite","@id":"https:\/\/www.belotti.com\/it\/#website","url":"https:\/\/www.belotti.com\/it\/","name":"Belotti Spa","description":"CNC Machining Centers","publisher":{"@id":"https:\/\/www.belotti.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.belotti.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.belotti.com\/it\/#organization","name":"Belotti Spa","url":"https:\/\/www.belotti.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.belotti.com\/it\/#\/schema\/logo\/image\/","url":"http:\/\/belotti.com\/wp-content\/uploads\/2023\/04\/logo-Belotti-1.png","contentUrl":"http:\/\/belotti.com\/wp-content\/uploads\/2023\/04\/logo-Belotti-1.png","width":708,"height":225,"caption":"Belotti Spa"},"image":{"@id":"https:\/\/www.belotti.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Belotti.SPA","https:\/\/x.com\/Belotti__SPA","https:\/\/www.youtube.com\/channel\/UC5q7E8IMymZ-agKfVsPCorw","https:\/\/www.linkedin.com\/company\/belotti-s-p-a-\/?viewAsMember=true","https:\/\/www.instagram.com\/belotti_spa\/"]},{"@type":"Person","@id":"https:\/\/www.belotti.com\/it\/#\/schema\/person\/b82447a049f0af88c70ba782b607ced6","name":"metodo","sameAs":["https:\/\/metodoadv.com\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/posts\/11965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/comments?post=11965"}],"version-history":[{"count":3,"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/posts\/11965\/revisions"}],"predecessor-version":[{"id":16622,"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/posts\/11965\/revisions\/16622"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/media\/7758"}],"wp:attachment":[{"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/media?parent=11965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/categories?post=11965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/tags?post=11965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}