{"id":23961,"date":"2025-03-17T10:30:12","date_gmt":"2025-03-17T09:30:12","guid":{"rendered":"https:\/\/belotti.com\/?p=23961"},"modified":"2026-01-08T12:17:15","modified_gmt":"2026-01-08T11:17:15","slug":"belotti-e-antonio-fuoco-pronti-per-correre-una-nuova-stagione-insieme","status":"publish","type":"post","link":"https:\/\/www.belotti.com\/it\/belotti-e-antonio-fuoco-pronti-per-correre-una-nuova-stagione-insieme\/","title":{"rendered":"Belotti e Antonio Fuoco: pronti per correre una nuova stagione insieme!"},"content":{"rendered":"<p><strong>La partnership con il pilota italiano, avviata lo scorso anno, viene rinnovata anche per la stagione 2025 del campionato FIA World Endurance Championship.<\/strong><\/p>\n<p>Ci sono vittorie che lasciano il segno, emozioni che restano impresse nella storia. <strong>Antonio Fuoco ha scritto una pagina indimenticabile del motorsport<\/strong>, conquistando insieme ai suoi compagni di squadra la prestigiosa <strong>\u201c24 Ore di Le Mans 2024\u201d<\/strong> con la Ferrari 499P n. 50, dimostrando talento, determinazione e una tenace passione per la velocit\u00e0.<\/p>\n<p>Per questo, con immenso orgoglio, Belotti ha deciso di rinnovare la partnership con Antonio, proseguendo un percorso che va oltre la semplice collaborazione: \u00e8 una <strong>condivisione di valori, di ambizione, di ricerca continua della perfezione<\/strong>. L\u2019endurance racing \u00e8 una sfida estrema, dove ogni dettaglio conta. Proprio come nelle nostre tecnologie, dove precisione, innovazione e prestazioni sono la chiave del successo. E Antonio, con la sua dedizione e il suo spirito combattivo, incarna alla perfezione questa filosofia.<\/p>\n<p>Il Campionato FIA WEC 2025 \u00e8 stato inaugurato lo scorso 28 febbraio sul Circuito di Lusail con la \u201c<strong>Qatar 1812km<\/strong>\u201d, dove <strong>Antonio e colleghi<\/strong> (Molina M., Nielsen N.) <strong>hanno dominato il podio nella gara di apertura<\/strong>. La stagione proseguir\u00e0 poi in Italia, Belgio, Francia, Brasile, Stati Uniti, Giappone e Bahrain. Appassionati e tifosi possono accedere al programma completo sul sito ufficiale <a href=\"https:\/\/www.fiawec.com\/en\/calendar\/80\" target=\"_blank\" rel=\"noopener\">FIA WEC<\/a> .<\/p>\n<p>Questa tredicesima stagione del FIA World Endurance Championship vedr\u00e0 la partecipazione di ben <strong>18 Hypercar di nove costruttori<\/strong>, evidenziando la continua crescita della pi\u00f9 importante serie di gare di durata del mondo. A contendersi la supremazia sui circuiti internazionali questa stagione saranno nomi stimati come Alpine, Aston Martin (subentrata a Lamborghini), BMW, Cadillac, Ferrari, Isotta Fraschini, Peugeot, Porsche e Toyota.<\/p>\n<p><strong>Siamo pronti per correre una nuova, entusiasmante stagione insieme<\/strong>. Avanti tutta, Antonio!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La partnership con il pilota italiano, avviata lo scorso anno, viene rinnovata anche per la stagione 2025 del&#8230;<\/p>\n","protected":false},"author":3,"featured_media":24067,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1868,1],"tags":[166,820,823,1338,1339,1340,1341,1342],"class_list":["post-23961","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2025-it","category-newsroom","tag-belotti-spa","tag-antonio-fuoco","tag-pilota-antonio-fuoco","tag-fia-world-endurance-championship","tag-wec-2025","tag-ferrari-hypercar","tag-fuoco","tag-ferrari-499p-50"],"acf":{"photo_gallery":{"galleria":[[]]}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Belotti e Antonio Fuoco: pronti per correre una nuova stagione insieme! - Belotti<\/title>\n<meta name=\"description\" content=\"La partnership con il pilota italiano, avviata lo scorso anno, viene rinnovata anche per la stagione 2025 del campionato FIA World Endurance Championship.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.belotti.com\/it\/belotti-e-antonio-fuoco-pronti-per-correre-una-nuova-stagione-insieme\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Belotti e Antonio Fuoco: pronti per correre una nuova stagione insieme! - Belotti\" \/>\n<meta property=\"og:description\" content=\"La partnership con il pilota italiano, avviata lo scorso anno, viene rinnovata anche per la stagione 2025 del campionato FIA World Endurance Championship.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.belotti.com\/it\/belotti-e-antonio-fuoco-pronti-per-correre-una-nuova-stagione-insieme\/\" \/>\n<meta property=\"og:site_name\" content=\"Belotti\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Belotti.SPA\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-17T09:30:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-08T11:17:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.belotti.com\/wp-content\/uploads\/2025\/03\/Belotti_Antonio-Fuoco-Rinnovo-partnership-2025.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1267\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eleonora Marino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Belotti__SPA\" \/>\n<meta name=\"twitter:site\" content=\"@Belotti__SPA\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eleonora Marino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/belotti-e-antonio-fuoco-pronti-per-correre-una-nuova-stagione-insieme\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/belotti-e-antonio-fuoco-pronti-per-correre-una-nuova-stagione-insieme\\\/\"},\"author\":{\"name\":\"Eleonora Marino\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#\\\/schema\\\/person\\\/59dd4c9f3a914fd557a57a4c56c1565e\"},\"headline\":\"Belotti e Antonio Fuoco: pronti per correre una nuova stagione insieme!\",\"datePublished\":\"2025-03-17T09:30:12+00:00\",\"dateModified\":\"2026-01-08T11:17:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/belotti-e-antonio-fuoco-pronti-per-correre-una-nuova-stagione-insieme\\\/\"},\"wordCount\":289,\"publisher\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/belotti-e-antonio-fuoco-pronti-per-correre-una-nuova-stagione-insieme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.belotti.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Belotti_Antonio-Fuoco-Rinnovo-partnership-2025.jpg\",\"keywords\":[\"Belotti spa\",\"Antonio Fuoco\",\"pilota Antonio Fuoco\",\"FIA World Endurance Championship\",\"WEC 2025\",\"Ferrari Hypercar\",\"Fuoco\",\"Ferrari 499P 50\"],\"articleSection\":[\"2025\",\"Newsroom\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/belotti-e-antonio-fuoco-pronti-per-correre-una-nuova-stagione-insieme\\\/\",\"url\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/belotti-e-antonio-fuoco-pronti-per-correre-una-nuova-stagione-insieme\\\/\",\"name\":\"Belotti e Antonio Fuoco: pronti per correre una nuova stagione insieme! - Belotti\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/belotti-e-antonio-fuoco-pronti-per-correre-una-nuova-stagione-insieme\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/belotti-e-antonio-fuoco-pronti-per-correre-una-nuova-stagione-insieme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.belotti.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Belotti_Antonio-Fuoco-Rinnovo-partnership-2025.jpg\",\"datePublished\":\"2025-03-17T09:30:12+00:00\",\"dateModified\":\"2026-01-08T11:17:15+00:00\",\"description\":\"La partnership con il pilota italiano, avviata lo scorso anno, viene rinnovata anche per la stagione 2025 del campionato FIA World Endurance Championship.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/belotti-e-antonio-fuoco-pronti-per-correre-una-nuova-stagione-insieme\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.belotti.com\\\/it\\\/belotti-e-antonio-fuoco-pronti-per-correre-una-nuova-stagione-insieme\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/belotti-e-antonio-fuoco-pronti-per-correre-una-nuova-stagione-insieme\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.belotti.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Belotti_Antonio-Fuoco-Rinnovo-partnership-2025.jpg\",\"contentUrl\":\"https:\\\/\\\/www.belotti.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Belotti_Antonio-Fuoco-Rinnovo-partnership-2025.jpg\",\"width\":1267,\"height\":720,\"caption\":\"Belotti SpA_Antonio Fuoco-partnership 2025\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/belotti-e-antonio-fuoco-pronti-per-correre-una-nuova-stagione-insieme\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Belotti e Antonio Fuoco: pronti per correre una nuova stagione insieme!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/\",\"name\":\"Belotti Spa\",\"description\":\"CNC Machining Centers\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#organization\",\"name\":\"Belotti Spa\",\"url\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/belotti.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo-Belotti-1.png\",\"contentUrl\":\"http:\\\/\\\/belotti.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo-Belotti-1.png\",\"width\":708,\"height\":225,\"caption\":\"Belotti Spa\"},\"image\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Belotti.SPA\",\"https:\\\/\\\/x.com\\\/Belotti__SPA\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC5q7E8IMymZ-agKfVsPCorw\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/belotti-s-p-a-\\\/?viewAsMember=true\",\"https:\\\/\\\/www.instagram.com\\\/belotti_spa\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#\\\/schema\\\/person\\\/59dd4c9f3a914fd557a57a4c56c1565e\",\"name\":\"Eleonora Marino\",\"sameAs\":[\"https:\\\/\\\/belotti.com\\\/it\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Belotti e Antonio Fuoco: pronti per correre una nuova stagione insieme! - Belotti","description":"La partnership con il pilota italiano, avviata lo scorso anno, viene rinnovata anche per la stagione 2025 del campionato FIA World Endurance Championship.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.belotti.com\/it\/belotti-e-antonio-fuoco-pronti-per-correre-una-nuova-stagione-insieme\/","og_locale":"it_IT","og_type":"article","og_title":"Belotti e Antonio Fuoco: pronti per correre una nuova stagione insieme! - Belotti","og_description":"La partnership con il pilota italiano, avviata lo scorso anno, viene rinnovata anche per la stagione 2025 del campionato FIA World Endurance Championship.","og_url":"https:\/\/www.belotti.com\/it\/belotti-e-antonio-fuoco-pronti-per-correre-una-nuova-stagione-insieme\/","og_site_name":"Belotti","article_publisher":"https:\/\/www.facebook.com\/Belotti.SPA","article_published_time":"2025-03-17T09:30:12+00:00","article_modified_time":"2026-01-08T11:17:15+00:00","og_image":[{"width":1267,"height":720,"url":"https:\/\/www.belotti.com\/wp-content\/uploads\/2025\/03\/Belotti_Antonio-Fuoco-Rinnovo-partnership-2025.jpg","type":"image\/jpeg"}],"author":"Eleonora Marino","twitter_card":"summary_large_image","twitter_creator":"@Belotti__SPA","twitter_site":"@Belotti__SPA","twitter_misc":{"Scritto da":"Eleonora Marino","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.belotti.com\/it\/belotti-e-antonio-fuoco-pronti-per-correre-una-nuova-stagione-insieme\/#article","isPartOf":{"@id":"https:\/\/www.belotti.com\/it\/belotti-e-antonio-fuoco-pronti-per-correre-una-nuova-stagione-insieme\/"},"author":{"name":"Eleonora Marino","@id":"https:\/\/www.belotti.com\/it\/#\/schema\/person\/59dd4c9f3a914fd557a57a4c56c1565e"},"headline":"Belotti e Antonio Fuoco: pronti per correre una nuova stagione insieme!","datePublished":"2025-03-17T09:30:12+00:00","dateModified":"2026-01-08T11:17:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.belotti.com\/it\/belotti-e-antonio-fuoco-pronti-per-correre-una-nuova-stagione-insieme\/"},"wordCount":289,"publisher":{"@id":"https:\/\/www.belotti.com\/it\/#organization"},"image":{"@id":"https:\/\/www.belotti.com\/it\/belotti-e-antonio-fuoco-pronti-per-correre-una-nuova-stagione-insieme\/#primaryimage"},"thumbnailUrl":"https:\/\/www.belotti.com\/wp-content\/uploads\/2025\/03\/Belotti_Antonio-Fuoco-Rinnovo-partnership-2025.jpg","keywords":["Belotti spa","Antonio Fuoco","pilota Antonio Fuoco","FIA World Endurance Championship","WEC 2025","Ferrari Hypercar","Fuoco","Ferrari 499P 50"],"articleSection":["2025","Newsroom"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.belotti.com\/it\/belotti-e-antonio-fuoco-pronti-per-correre-una-nuova-stagione-insieme\/","url":"https:\/\/www.belotti.com\/it\/belotti-e-antonio-fuoco-pronti-per-correre-una-nuova-stagione-insieme\/","name":"Belotti e Antonio Fuoco: pronti per correre una nuova stagione insieme! - Belotti","isPartOf":{"@id":"https:\/\/www.belotti.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.belotti.com\/it\/belotti-e-antonio-fuoco-pronti-per-correre-una-nuova-stagione-insieme\/#primaryimage"},"image":{"@id":"https:\/\/www.belotti.com\/it\/belotti-e-antonio-fuoco-pronti-per-correre-una-nuova-stagione-insieme\/#primaryimage"},"thumbnailUrl":"https:\/\/www.belotti.com\/wp-content\/uploads\/2025\/03\/Belotti_Antonio-Fuoco-Rinnovo-partnership-2025.jpg","datePublished":"2025-03-17T09:30:12+00:00","dateModified":"2026-01-08T11:17:15+00:00","description":"La partnership con il pilota italiano, avviata lo scorso anno, viene rinnovata anche per la stagione 2025 del campionato FIA World Endurance Championship.","breadcrumb":{"@id":"https:\/\/www.belotti.com\/it\/belotti-e-antonio-fuoco-pronti-per-correre-una-nuova-stagione-insieme\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.belotti.com\/it\/belotti-e-antonio-fuoco-pronti-per-correre-una-nuova-stagione-insieme\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.belotti.com\/it\/belotti-e-antonio-fuoco-pronti-per-correre-una-nuova-stagione-insieme\/#primaryimage","url":"https:\/\/www.belotti.com\/wp-content\/uploads\/2025\/03\/Belotti_Antonio-Fuoco-Rinnovo-partnership-2025.jpg","contentUrl":"https:\/\/www.belotti.com\/wp-content\/uploads\/2025\/03\/Belotti_Antonio-Fuoco-Rinnovo-partnership-2025.jpg","width":1267,"height":720,"caption":"Belotti SpA_Antonio Fuoco-partnership 2025"},{"@type":"BreadcrumbList","@id":"https:\/\/www.belotti.com\/it\/belotti-e-antonio-fuoco-pronti-per-correre-una-nuova-stagione-insieme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.belotti.com\/it\/"},{"@type":"ListItem","position":2,"name":"Belotti e Antonio Fuoco: pronti per correre una nuova stagione insieme!"}]},{"@type":"WebSite","@id":"https:\/\/www.belotti.com\/it\/#website","url":"https:\/\/www.belotti.com\/it\/","name":"Belotti Spa","description":"CNC Machining Centers","publisher":{"@id":"https:\/\/www.belotti.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.belotti.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.belotti.com\/it\/#organization","name":"Belotti Spa","url":"https:\/\/www.belotti.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.belotti.com\/it\/#\/schema\/logo\/image\/","url":"http:\/\/belotti.com\/wp-content\/uploads\/2023\/04\/logo-Belotti-1.png","contentUrl":"http:\/\/belotti.com\/wp-content\/uploads\/2023\/04\/logo-Belotti-1.png","width":708,"height":225,"caption":"Belotti Spa"},"image":{"@id":"https:\/\/www.belotti.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Belotti.SPA","https:\/\/x.com\/Belotti__SPA","https:\/\/www.youtube.com\/channel\/UC5q7E8IMymZ-agKfVsPCorw","https:\/\/www.linkedin.com\/company\/belotti-s-p-a-\/?viewAsMember=true","https:\/\/www.instagram.com\/belotti_spa\/"]},{"@type":"Person","@id":"https:\/\/www.belotti.com\/it\/#\/schema\/person\/59dd4c9f3a914fd557a57a4c56c1565e","name":"Eleonora Marino","sameAs":["https:\/\/belotti.com\/it\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/posts\/23961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/comments?post=23961"}],"version-history":[{"count":3,"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/posts\/23961\/revisions"}],"predecessor-version":[{"id":24180,"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/posts\/23961\/revisions\/24180"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/media\/24067"}],"wp:attachment":[{"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/media?parent=23961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/categories?post=23961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/tags?post=23961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}