{"id":27171,"date":"2025-12-02T09:11:46","date_gmt":"2025-12-02T08:11:46","guid":{"rendered":"https:\/\/www.belotti.com\/jec-world-paris-march-10-12-2026-see-you-there\/"},"modified":"2026-01-22T17:28:48","modified_gmt":"2026-01-22T16:28:48","slug":"jec-world-parigi-10-12-marzo-2026-vi-aspettiamo","status":"publish","type":"post","link":"https:\/\/www.belotti.com\/it\/jec-world-parigi-10-12-marzo-2026-vi-aspettiamo\/","title":{"rendered":"JEC WORLD PARIGI, 10-12 MARZO 2026. VI ASPETTIAMO!"},"content":{"rendered":"<p>Torna a <strong>marzo 2026<\/strong> l\u2019appuntamento con <strong>JEC World<\/strong>, la fiera di riferimento per il settore dei materiali compositi, in programma <strong>da marted\u00ec 10 a gioved\u00ec 12<\/strong> presso il centro espositivo <strong>Paris Nord Villepinte<\/strong>.<\/p>\n<p>Questa edizione assume per la nostra azienda un significato speciale: nel <strong>cinquantesimo anniversario<\/strong> dalla fondazione, la pi\u00f9 importante fiera internazionale dedicata ai materiali compositi e alle loro applicazioni sar\u00e0 il palcoscenico ideale per raccontare al mercato internazionale ci\u00f2 che ci caratterizza: <strong>esperienza<\/strong>, <strong>solidit\u00e0 e una forte passione per l\u2019innovazione tecnologica<\/strong>.<\/p>\n<p>Vi aspettiamo al nostro <strong>stand G61 \u2013 Padiglione 6 per festeggiare<\/strong> insieme questa tappa importante del nostro viaggio e per <strong>scoprire le ultime novit\u00e0 di prodotto<\/strong> sviluppate in collaborazione con i nostri partner tecnologici.<\/p>\n<p>In particolare, quest\u2019anno lo stand sar\u00e0 il palcoscenico per il <strong>lancio ufficiale di una nuova tecnologia ibrida<\/strong> per la stampa 3D di grande formato e la fresatura CNC di <strong>materiali termoindurenti<\/strong>, alla quale \u00e8 dedicata la <strong>conferenza \u201cThermosetting composites additive manufacturing: towards hybrid technologies\u201d<\/strong>, in calendario <strong>mercoled\u00ec 11 marzo<\/strong> alle <strong>ore 12:00<\/strong> presso l\u2019<strong>Agor\u00e0 6<\/strong> all\u2019interno del programma <a href=\"https:\/\/www.jec-world.events\/program\/conferences\/composites-exchange\" target=\"_blank\" rel=\"noopener\">Composites Exchange<\/a>. <strong>Alberto Riganti<\/strong>, Belotti SpA Sales Product Manager, e <strong>Tommaso Geri<\/strong>, CTO di Moi Composites, metteranno in evidenza:<\/p>\n<ul>\n<li>caratteristiche e potenzialit\u00e0 applicative della stampa 3D di materiali termoindurenti<\/li>\n<li>vantaggi produttivi derivanti dall\u2019integrazione di questo processo all\u2019interno di un centro di lavoro a controllo numerico.<\/li>\n<li style=\"list-style-type: none;\"><\/li>\n<\/ul>\n<p>Per partecipare alla conferenza e ricevere il pass d\u2019ingresso vi invitiamo a compilare il form.<\/p>\n<p>Seguiteci sui canali <a href=\"https:\/\/www.linkedin.com\/company\/10010465\/admin\/dashboard\/\" target=\"_blank\" rel=\"noopener\">LinkedIn<\/a> e <a href=\"https:\/\/www.instagram.com\/belotti_spa\/\" target=\"_blank\" rel=\"noopener\">Instagram<\/a> per rimanere aggiornati su tutte le iniziative in programma durante JEC World 2026.<\/p>\n<p>Vi aspettiamo!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torna a marzo 2026 l\u2019appuntamento con JEC World, la fiera di riferimento per il settore dei materiali compositi,&#8230;<\/p>\n","protected":false},"author":3,"featured_media":27165,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[9],"tags":[166,1061,1792],"class_list":["post-27171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi","tag-belotti-spa","tag-paris-nord-villepinte","tag-jec-world-2026"],"acf":{"photo_gallery":{"galleria":[[]]}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>JEC WORLD PARIGI, 10-12 MARZO 2026. VI ASPETTIAMO! - Belotti<\/title>\n<meta name=\"description\" content=\"Torna a marzo 2026 l\u2019appuntamento con JEC World, la fiera di riferimento per il settore dei materiali compositi, in programma da marted\u00ec 10 a gioved\u00ec 12\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.belotti.com\/it\/jec-world-parigi-10-12-marzo-2026-vi-aspettiamo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JEC WORLD PARIGI, 10-12 MARZO 2026. VI ASPETTIAMO! - Belotti\" \/>\n<meta property=\"og:description\" content=\"Torna a marzo 2026 l\u2019appuntamento con JEC World, la fiera di riferimento per il settore dei materiali compositi, in programma da marted\u00ec 10 a gioved\u00ec 12\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.belotti.com\/it\/jec-world-parigi-10-12-marzo-2026-vi-aspettiamo\/\" \/>\n<meta property=\"og:site_name\" content=\"Belotti\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Belotti.SPA\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-02T08:11:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-22T16:28:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.belotti.com\/wp-content\/uploads\/2025\/12\/Belotti-at-JEC-World-Paris-2026.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"790\" \/>\n\t<meta property=\"og:image:height\" content=\"446\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eleonora Marino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Belotti__SPA\" \/>\n<meta name=\"twitter:site\" content=\"@Belotti__SPA\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eleonora Marino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/jec-world-parigi-10-12-marzo-2026-vi-aspettiamo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/jec-world-parigi-10-12-marzo-2026-vi-aspettiamo\\\/\"},\"author\":{\"name\":\"Eleonora Marino\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#\\\/schema\\\/person\\\/59dd4c9f3a914fd557a57a4c56c1565e\"},\"headline\":\"JEC WORLD PARIGI, 10-12 MARZO 2026. VI ASPETTIAMO!\",\"datePublished\":\"2025-12-02T08:11:46+00:00\",\"dateModified\":\"2026-01-22T16:28:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/jec-world-parigi-10-12-marzo-2026-vi-aspettiamo\\\/\"},\"wordCount\":261,\"publisher\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/jec-world-parigi-10-12-marzo-2026-vi-aspettiamo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.belotti.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Belotti-at-JEC-World-Paris-2026.jpg\",\"keywords\":[\"Belotti spa\",\"Paris Nord Villepinte\",\"JEC World 2026\"],\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/jec-world-parigi-10-12-marzo-2026-vi-aspettiamo\\\/\",\"url\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/jec-world-parigi-10-12-marzo-2026-vi-aspettiamo\\\/\",\"name\":\"JEC WORLD PARIGI, 10-12 MARZO 2026. VI ASPETTIAMO! - Belotti\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/jec-world-parigi-10-12-marzo-2026-vi-aspettiamo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/jec-world-parigi-10-12-marzo-2026-vi-aspettiamo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.belotti.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Belotti-at-JEC-World-Paris-2026.jpg\",\"datePublished\":\"2025-12-02T08:11:46+00:00\",\"dateModified\":\"2026-01-22T16:28:48+00:00\",\"description\":\"Torna a marzo 2026 l\u2019appuntamento con JEC World, la fiera di riferimento per il settore dei materiali compositi, in programma da marted\u00ec 10 a gioved\u00ec 12\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/jec-world-parigi-10-12-marzo-2026-vi-aspettiamo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.belotti.com\\\/it\\\/jec-world-parigi-10-12-marzo-2026-vi-aspettiamo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/jec-world-parigi-10-12-marzo-2026-vi-aspettiamo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.belotti.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Belotti-at-JEC-World-Paris-2026.jpg\",\"contentUrl\":\"https:\\\/\\\/www.belotti.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Belotti-at-JEC-World-Paris-2026.jpg\",\"width\":790,\"height\":446,\"caption\":\"Belotti a JEC World Paris 2026\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/jec-world-parigi-10-12-marzo-2026-vi-aspettiamo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"JEC WORLD PARIGI, 10-12 MARZO 2026. VI ASPETTIAMO!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/\",\"name\":\"Belotti Spa\",\"description\":\"CNC Machining Centers\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#organization\",\"name\":\"Belotti Spa\",\"url\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/belotti.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo-Belotti-1.png\",\"contentUrl\":\"http:\\\/\\\/belotti.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo-Belotti-1.png\",\"width\":708,\"height\":225,\"caption\":\"Belotti Spa\"},\"image\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Belotti.SPA\",\"https:\\\/\\\/x.com\\\/Belotti__SPA\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC5q7E8IMymZ-agKfVsPCorw\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/belotti-s-p-a-\\\/?viewAsMember=true\",\"https:\\\/\\\/www.instagram.com\\\/belotti_spa\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#\\\/schema\\\/person\\\/59dd4c9f3a914fd557a57a4c56c1565e\",\"name\":\"Eleonora Marino\",\"sameAs\":[\"https:\\\/\\\/belotti.com\\\/it\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"JEC WORLD PARIGI, 10-12 MARZO 2026. VI ASPETTIAMO! - Belotti","description":"Torna a marzo 2026 l\u2019appuntamento con JEC World, la fiera di riferimento per il settore dei materiali compositi, in programma da marted\u00ec 10 a gioved\u00ec 12","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.belotti.com\/it\/jec-world-parigi-10-12-marzo-2026-vi-aspettiamo\/","og_locale":"it_IT","og_type":"article","og_title":"JEC WORLD PARIGI, 10-12 MARZO 2026. VI ASPETTIAMO! - Belotti","og_description":"Torna a marzo 2026 l\u2019appuntamento con JEC World, la fiera di riferimento per il settore dei materiali compositi, in programma da marted\u00ec 10 a gioved\u00ec 12","og_url":"https:\/\/www.belotti.com\/it\/jec-world-parigi-10-12-marzo-2026-vi-aspettiamo\/","og_site_name":"Belotti","article_publisher":"https:\/\/www.facebook.com\/Belotti.SPA","article_published_time":"2025-12-02T08:11:46+00:00","article_modified_time":"2026-01-22T16:28:48+00:00","og_image":[{"width":790,"height":446,"url":"https:\/\/www.belotti.com\/wp-content\/uploads\/2025\/12\/Belotti-at-JEC-World-Paris-2026.jpg","type":"image\/jpeg"}],"author":"Eleonora Marino","twitter_card":"summary_large_image","twitter_creator":"@Belotti__SPA","twitter_site":"@Belotti__SPA","twitter_misc":{"Scritto da":"Eleonora Marino","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.belotti.com\/it\/jec-world-parigi-10-12-marzo-2026-vi-aspettiamo\/#article","isPartOf":{"@id":"https:\/\/www.belotti.com\/it\/jec-world-parigi-10-12-marzo-2026-vi-aspettiamo\/"},"author":{"name":"Eleonora Marino","@id":"https:\/\/www.belotti.com\/it\/#\/schema\/person\/59dd4c9f3a914fd557a57a4c56c1565e"},"headline":"JEC WORLD PARIGI, 10-12 MARZO 2026. VI ASPETTIAMO!","datePublished":"2025-12-02T08:11:46+00:00","dateModified":"2026-01-22T16:28:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.belotti.com\/it\/jec-world-parigi-10-12-marzo-2026-vi-aspettiamo\/"},"wordCount":261,"publisher":{"@id":"https:\/\/www.belotti.com\/it\/#organization"},"image":{"@id":"https:\/\/www.belotti.com\/it\/jec-world-parigi-10-12-marzo-2026-vi-aspettiamo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.belotti.com\/wp-content\/uploads\/2025\/12\/Belotti-at-JEC-World-Paris-2026.jpg","keywords":["Belotti spa","Paris Nord Villepinte","JEC World 2026"],"articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.belotti.com\/it\/jec-world-parigi-10-12-marzo-2026-vi-aspettiamo\/","url":"https:\/\/www.belotti.com\/it\/jec-world-parigi-10-12-marzo-2026-vi-aspettiamo\/","name":"JEC WORLD PARIGI, 10-12 MARZO 2026. VI ASPETTIAMO! - Belotti","isPartOf":{"@id":"https:\/\/www.belotti.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.belotti.com\/it\/jec-world-parigi-10-12-marzo-2026-vi-aspettiamo\/#primaryimage"},"image":{"@id":"https:\/\/www.belotti.com\/it\/jec-world-parigi-10-12-marzo-2026-vi-aspettiamo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.belotti.com\/wp-content\/uploads\/2025\/12\/Belotti-at-JEC-World-Paris-2026.jpg","datePublished":"2025-12-02T08:11:46+00:00","dateModified":"2026-01-22T16:28:48+00:00","description":"Torna a marzo 2026 l\u2019appuntamento con JEC World, la fiera di riferimento per il settore dei materiali compositi, in programma da marted\u00ec 10 a gioved\u00ec 12","breadcrumb":{"@id":"https:\/\/www.belotti.com\/it\/jec-world-parigi-10-12-marzo-2026-vi-aspettiamo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.belotti.com\/it\/jec-world-parigi-10-12-marzo-2026-vi-aspettiamo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.belotti.com\/it\/jec-world-parigi-10-12-marzo-2026-vi-aspettiamo\/#primaryimage","url":"https:\/\/www.belotti.com\/wp-content\/uploads\/2025\/12\/Belotti-at-JEC-World-Paris-2026.jpg","contentUrl":"https:\/\/www.belotti.com\/wp-content\/uploads\/2025\/12\/Belotti-at-JEC-World-Paris-2026.jpg","width":790,"height":446,"caption":"Belotti a JEC World Paris 2026"},{"@type":"BreadcrumbList","@id":"https:\/\/www.belotti.com\/it\/jec-world-parigi-10-12-marzo-2026-vi-aspettiamo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.belotti.com\/it\/"},{"@type":"ListItem","position":2,"name":"JEC WORLD PARIGI, 10-12 MARZO 2026. VI ASPETTIAMO!"}]},{"@type":"WebSite","@id":"https:\/\/www.belotti.com\/it\/#website","url":"https:\/\/www.belotti.com\/it\/","name":"Belotti Spa","description":"CNC Machining Centers","publisher":{"@id":"https:\/\/www.belotti.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.belotti.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.belotti.com\/it\/#organization","name":"Belotti Spa","url":"https:\/\/www.belotti.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.belotti.com\/it\/#\/schema\/logo\/image\/","url":"http:\/\/belotti.com\/wp-content\/uploads\/2023\/04\/logo-Belotti-1.png","contentUrl":"http:\/\/belotti.com\/wp-content\/uploads\/2023\/04\/logo-Belotti-1.png","width":708,"height":225,"caption":"Belotti Spa"},"image":{"@id":"https:\/\/www.belotti.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Belotti.SPA","https:\/\/x.com\/Belotti__SPA","https:\/\/www.youtube.com\/channel\/UC5q7E8IMymZ-agKfVsPCorw","https:\/\/www.linkedin.com\/company\/belotti-s-p-a-\/?viewAsMember=true","https:\/\/www.instagram.com\/belotti_spa\/"]},{"@type":"Person","@id":"https:\/\/www.belotti.com\/it\/#\/schema\/person\/59dd4c9f3a914fd557a57a4c56c1565e","name":"Eleonora Marino","sameAs":["https:\/\/belotti.com\/it\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/posts\/27171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/comments?post=27171"}],"version-history":[{"count":3,"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/posts\/27171\/revisions"}],"predecessor-version":[{"id":28124,"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/posts\/27171\/revisions\/28124"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/media\/27165"}],"wp:attachment":[{"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/media?parent=27171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/categories?post=27171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/tags?post=27171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}