{"id":7528,"date":"2022-02-25T10:42:32","date_gmt":"2022-02-25T09:42:32","guid":{"rendered":"https:\/\/belotti.com\/?p=7528"},"modified":"2023-11-24T17:22:13","modified_gmt":"2023-11-24T16:22:13","slug":"belotti-torna-ad-esporre-alla-fiera-mach-di-birmingham","status":"publish","type":"post","link":"https:\/\/www.belotti.com\/it\/belotti-torna-ad-esporre-alla-fiera-mach-di-birmingham\/","title":{"rendered":"Belotti torna ad esporre alla fiera MACH di Birmingham"},"content":{"rendered":"<p>Torna, <strong>dal 4 al 8 Aprile, MACH<\/strong>, la pi\u00f9 importante fiera del Regno Unito dedicata alle nuove tecnologie e alle soluzioni di ingegneria avanzata: automazione e robotica, 3d printing e additive manufacturing, strumenti di misurazione e controllo, macchinari per la finitura superficiale e sistemi laser sono alcune delle principali aree tematiche allestite all\u2019interno dei padiglioni.<\/p>\n<p>L\u2019evento \u00e8 organizzato da <strong>MTA<\/strong>, l\u2019Associazione di categoria per le imprese operanti nel settore manifatturiero, e si svolger\u00e0 presso il <strong>National Exhibition Centre<\/strong> di Birmingham.<\/p>\n<p>Anche per questa edizione la nostra partecipazione coinvolger\u00e0 <a title=\"www.cannonshelley.com\" href=\"http:\/\/www.cannonshelley.com\/en\/index.html\" target=\"_blank\" rel=\"nofollow noopener\"><strong>Cannon Shelley<\/strong><\/a>, distributore ufficiale per il mercato inglese. Con l\u2019occasione presenteremo le ultime soluzioni per la lavorazione dei materiali tramite <a href=\"https:\/\/www.belotti.com\/it\/centri-di-lavoro-cnc\/\"><strong>centri di lavoro a controllo numerico<\/strong><\/a> e gli applicativi <strong>software<\/strong> per la loro gestione integrata nell\u2019ambiente fabbrica (Industria 4.0). In questo contesto si inseriscono anche le attivit\u00e0 di <a href=\"https:\/\/www.belotti.com\/it\/automazione-industriale\/linee-e-celle-di-lavoro-robotizzate\/\"><strong>Belotti Robotic Automation<\/strong><\/a>, la divisione Belotti dedicata allo sviluppo, alla progettazione e alla produzione di linee e celle robotiche. Non mancher\u00e0 ovviamente la possibilit\u00e0 di approfondire le caratteristiche tecniche e le potenzialit\u00e0 di <strong>BEAD<\/strong>, la soluzione integrata per la stampa additiva di grande formato e la fresatura.<\/p>\n<p>Vi aspettiamo presso il nostro <strong>stand n. 554 all\u2019interno del padiglione 17<\/strong>: per ottenere il pass di ingresso vi invitiamo a <a title=\"registravi qui\" href=\"https:\/\/registration.gesevent.com\/survey\/29yxn0q97uzy8?actioncode=NTWO000794QNH&amp;partner-contact=1smveneyh8qaf\" target=\"_blank\" rel=\"nofollow noopener\">registravi qui<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torna, dal 4 al 8 Aprile, MACH, la pi\u00f9 importante fiera del Regno Unito dedicata alle nuove tecnologie&#8230;<\/p>\n","protected":false},"author":3,"featured_media":7558,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[73,9,707],"tags":[318,319,320,321,317],"class_list":["post-7528","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-2","category-eventi","category-2022-it","tag-fiera-mach-2022","tag-mach-2022-birmingham","tag-fiera-uk-tecnologie-produttive","tag-cannon-shelley","tag-mach-2022"],"acf":{"photo_gallery":{"galleria":[[]]}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Belotti torna ad esporre alla fiera MACH di Birmingham - Belotti<\/title>\n<meta name=\"description\" content=\"Torna, dal 4 al 8 Aprile, MACH, la pi\u00f9 importante fiera del Regno Unito dedicata alle nuove tecnologie e alle soluzioni di ingegneria avanzata:\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.belotti.com\/it\/belotti-torna-ad-esporre-alla-fiera-mach-di-birmingham\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Belotti torna ad esporre alla fiera MACH di Birmingham - Belotti\" \/>\n<meta property=\"og:description\" content=\"Torna, dal 4 al 8 Aprile, MACH, la pi\u00f9 importante fiera del Regno Unito dedicata alle nuove tecnologie e alle soluzioni di ingegneria avanzata:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.belotti.com\/it\/belotti-torna-ad-esporre-alla-fiera-mach-di-birmingham\/\" \/>\n<meta property=\"og:site_name\" content=\"Belotti\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Belotti.SPA\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-25T09:42:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-24T16:22:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.belotti.com\/wp-content\/uploads\/2022\/02\/event-belotti-mach2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"790\" \/>\n\t<meta property=\"og:image:height\" content=\"446\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eleonora Marino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Belotti__SPA\" \/>\n<meta name=\"twitter:site\" content=\"@Belotti__SPA\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eleonora Marino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/belotti-torna-ad-esporre-alla-fiera-mach-di-birmingham\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/belotti-torna-ad-esporre-alla-fiera-mach-di-birmingham\\\/\"},\"author\":{\"name\":\"Eleonora Marino\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#\\\/schema\\\/person\\\/59dd4c9f3a914fd557a57a4c56c1565e\"},\"headline\":\"Belotti torna ad esporre alla fiera MACH di Birmingham\",\"datePublished\":\"2022-02-25T09:42:32+00:00\",\"dateModified\":\"2023-11-24T16:22:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/belotti-torna-ad-esporre-alla-fiera-mach-di-birmingham\\\/\"},\"wordCount\":215,\"publisher\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/belotti-torna-ad-esporre-alla-fiera-mach-di-birmingham\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.belotti.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/event-belotti-mach2.jpg\",\"keywords\":[\"Fiera Mach 2022\",\"Mach 2022 Birmingham\",\"Fiera UK tecnologie produttive\",\"Cannon Shelley\",\"Mach 2022\"],\"articleSection\":[\"Archivio\",\"Eventi\",\"2022\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/belotti-torna-ad-esporre-alla-fiera-mach-di-birmingham\\\/\",\"url\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/belotti-torna-ad-esporre-alla-fiera-mach-di-birmingham\\\/\",\"name\":\"Belotti torna ad esporre alla fiera MACH di Birmingham - Belotti\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/belotti-torna-ad-esporre-alla-fiera-mach-di-birmingham\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/belotti-torna-ad-esporre-alla-fiera-mach-di-birmingham\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.belotti.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/event-belotti-mach2.jpg\",\"datePublished\":\"2022-02-25T09:42:32+00:00\",\"dateModified\":\"2023-11-24T16:22:13+00:00\",\"description\":\"Torna, dal 4 al 8 Aprile, MACH, la pi\u00f9 importante fiera del Regno Unito dedicata alle nuove tecnologie e alle soluzioni di ingegneria avanzata:\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/belotti-torna-ad-esporre-alla-fiera-mach-di-birmingham\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.belotti.com\\\/it\\\/belotti-torna-ad-esporre-alla-fiera-mach-di-birmingham\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/belotti-torna-ad-esporre-alla-fiera-mach-di-birmingham\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.belotti.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/event-belotti-mach2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.belotti.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/event-belotti-mach2.jpg\",\"width\":790,\"height\":446,\"caption\":\"event-belotti-mach\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/belotti-torna-ad-esporre-alla-fiera-mach-di-birmingham\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Belotti torna ad esporre alla fiera MACH di Birmingham\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/\",\"name\":\"Belotti Spa\",\"description\":\"CNC Machining Centers\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#organization\",\"name\":\"Belotti Spa\",\"url\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/belotti.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo-Belotti-1.png\",\"contentUrl\":\"http:\\\/\\\/belotti.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo-Belotti-1.png\",\"width\":708,\"height\":225,\"caption\":\"Belotti Spa\"},\"image\":{\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Belotti.SPA\",\"https:\\\/\\\/x.com\\\/Belotti__SPA\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC5q7E8IMymZ-agKfVsPCorw\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/belotti-s-p-a-\\\/?viewAsMember=true\",\"https:\\\/\\\/www.instagram.com\\\/belotti_spa\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.belotti.com\\\/it\\\/#\\\/schema\\\/person\\\/59dd4c9f3a914fd557a57a4c56c1565e\",\"name\":\"Eleonora Marino\",\"sameAs\":[\"https:\\\/\\\/belotti.com\\\/it\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Belotti torna ad esporre alla fiera MACH di Birmingham - Belotti","description":"Torna, dal 4 al 8 Aprile, MACH, la pi\u00f9 importante fiera del Regno Unito dedicata alle nuove tecnologie e alle soluzioni di ingegneria avanzata:","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.belotti.com\/it\/belotti-torna-ad-esporre-alla-fiera-mach-di-birmingham\/","og_locale":"it_IT","og_type":"article","og_title":"Belotti torna ad esporre alla fiera MACH di Birmingham - Belotti","og_description":"Torna, dal 4 al 8 Aprile, MACH, la pi\u00f9 importante fiera del Regno Unito dedicata alle nuove tecnologie e alle soluzioni di ingegneria avanzata:","og_url":"https:\/\/www.belotti.com\/it\/belotti-torna-ad-esporre-alla-fiera-mach-di-birmingham\/","og_site_name":"Belotti","article_publisher":"https:\/\/www.facebook.com\/Belotti.SPA","article_published_time":"2022-02-25T09:42:32+00:00","article_modified_time":"2023-11-24T16:22:13+00:00","og_image":[{"width":790,"height":446,"url":"https:\/\/www.belotti.com\/wp-content\/uploads\/2022\/02\/event-belotti-mach2.jpg","type":"image\/jpeg"}],"author":"Eleonora Marino","twitter_card":"summary_large_image","twitter_creator":"@Belotti__SPA","twitter_site":"@Belotti__SPA","twitter_misc":{"Scritto da":"Eleonora Marino","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.belotti.com\/it\/belotti-torna-ad-esporre-alla-fiera-mach-di-birmingham\/#article","isPartOf":{"@id":"https:\/\/www.belotti.com\/it\/belotti-torna-ad-esporre-alla-fiera-mach-di-birmingham\/"},"author":{"name":"Eleonora Marino","@id":"https:\/\/www.belotti.com\/it\/#\/schema\/person\/59dd4c9f3a914fd557a57a4c56c1565e"},"headline":"Belotti torna ad esporre alla fiera MACH di Birmingham","datePublished":"2022-02-25T09:42:32+00:00","dateModified":"2023-11-24T16:22:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.belotti.com\/it\/belotti-torna-ad-esporre-alla-fiera-mach-di-birmingham\/"},"wordCount":215,"publisher":{"@id":"https:\/\/www.belotti.com\/it\/#organization"},"image":{"@id":"https:\/\/www.belotti.com\/it\/belotti-torna-ad-esporre-alla-fiera-mach-di-birmingham\/#primaryimage"},"thumbnailUrl":"https:\/\/www.belotti.com\/wp-content\/uploads\/2022\/02\/event-belotti-mach2.jpg","keywords":["Fiera Mach 2022","Mach 2022 Birmingham","Fiera UK tecnologie produttive","Cannon Shelley","Mach 2022"],"articleSection":["Archivio","Eventi","2022"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.belotti.com\/it\/belotti-torna-ad-esporre-alla-fiera-mach-di-birmingham\/","url":"https:\/\/www.belotti.com\/it\/belotti-torna-ad-esporre-alla-fiera-mach-di-birmingham\/","name":"Belotti torna ad esporre alla fiera MACH di Birmingham - Belotti","isPartOf":{"@id":"https:\/\/www.belotti.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.belotti.com\/it\/belotti-torna-ad-esporre-alla-fiera-mach-di-birmingham\/#primaryimage"},"image":{"@id":"https:\/\/www.belotti.com\/it\/belotti-torna-ad-esporre-alla-fiera-mach-di-birmingham\/#primaryimage"},"thumbnailUrl":"https:\/\/www.belotti.com\/wp-content\/uploads\/2022\/02\/event-belotti-mach2.jpg","datePublished":"2022-02-25T09:42:32+00:00","dateModified":"2023-11-24T16:22:13+00:00","description":"Torna, dal 4 al 8 Aprile, MACH, la pi\u00f9 importante fiera del Regno Unito dedicata alle nuove tecnologie e alle soluzioni di ingegneria avanzata:","breadcrumb":{"@id":"https:\/\/www.belotti.com\/it\/belotti-torna-ad-esporre-alla-fiera-mach-di-birmingham\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.belotti.com\/it\/belotti-torna-ad-esporre-alla-fiera-mach-di-birmingham\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.belotti.com\/it\/belotti-torna-ad-esporre-alla-fiera-mach-di-birmingham\/#primaryimage","url":"https:\/\/www.belotti.com\/wp-content\/uploads\/2022\/02\/event-belotti-mach2.jpg","contentUrl":"https:\/\/www.belotti.com\/wp-content\/uploads\/2022\/02\/event-belotti-mach2.jpg","width":790,"height":446,"caption":"event-belotti-mach"},{"@type":"BreadcrumbList","@id":"https:\/\/www.belotti.com\/it\/belotti-torna-ad-esporre-alla-fiera-mach-di-birmingham\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.belotti.com\/it\/"},{"@type":"ListItem","position":2,"name":"Belotti torna ad esporre alla fiera MACH di Birmingham"}]},{"@type":"WebSite","@id":"https:\/\/www.belotti.com\/it\/#website","url":"https:\/\/www.belotti.com\/it\/","name":"Belotti Spa","description":"CNC Machining Centers","publisher":{"@id":"https:\/\/www.belotti.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.belotti.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.belotti.com\/it\/#organization","name":"Belotti Spa","url":"https:\/\/www.belotti.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.belotti.com\/it\/#\/schema\/logo\/image\/","url":"http:\/\/belotti.com\/wp-content\/uploads\/2023\/04\/logo-Belotti-1.png","contentUrl":"http:\/\/belotti.com\/wp-content\/uploads\/2023\/04\/logo-Belotti-1.png","width":708,"height":225,"caption":"Belotti Spa"},"image":{"@id":"https:\/\/www.belotti.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Belotti.SPA","https:\/\/x.com\/Belotti__SPA","https:\/\/www.youtube.com\/channel\/UC5q7E8IMymZ-agKfVsPCorw","https:\/\/www.linkedin.com\/company\/belotti-s-p-a-\/?viewAsMember=true","https:\/\/www.instagram.com\/belotti_spa\/"]},{"@type":"Person","@id":"https:\/\/www.belotti.com\/it\/#\/schema\/person\/59dd4c9f3a914fd557a57a4c56c1565e","name":"Eleonora Marino","sameAs":["https:\/\/belotti.com\/it\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/posts\/7528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/comments?post=7528"}],"version-history":[{"count":14,"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/posts\/7528\/revisions"}],"predecessor-version":[{"id":16335,"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/posts\/7528\/revisions\/16335"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/media\/7558"}],"wp:attachment":[{"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/media?parent=7528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/categories?post=7528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.belotti.com\/it\/wp-json\/wp\/v2\/tags?post=7528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}